{"id":3816,"date":"2024-12-01T00:50:46","date_gmt":"2024-11-30T16:50:46","guid":{"rendered":"https:\/\/susi.xhddp.com\/?page_id=3816"},"modified":"2025-08-21T14:07:46","modified_gmt":"2025-08-21T06:07:46","slug":"solutions-de-fret-speciales","status":"publish","type":"page","link":"https:\/\/susi.xhddp.com\/fr\/service\/solutions-de-fret-speciales","title":{"rendered":"Solutions de fret sp\u00e9ciales"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3816\" class=\"elementor elementor-3816\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe9c2bb e-con-full e-flex e-con e-parent\" data-id=\"fe9c2bb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:200}\">\n\t\t<div class=\"elementor-element elementor-element-ffeaf53 e-flex e-con-boxed e-con e-child\" data-id=\"ffeaf53\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db001ef elementor-widget elementor-widget-spacer\" data-id=\"db001ef\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2728f4c e-con-full e-flex e-con e-child\" data-id=\"2728f4c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cce0938 elementor-widget elementor-widget-heading\" data-id=\"cce0938\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">navire de marchandises sensibles et sp\u00e9ciales en provenance de Chine\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd80ec4 elementor-widget elementor-widget-text-editor\" data-id=\"cd80ec4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#039;\u00e9quipe XH est compos\u00e9e de professionnels de la manutention de marchandises dangereuses en provenance de Chine par voie a\u00e9rienne et maritime. Nous fournissons des tarifs d&#039;exp\u00e9dition dans des d\u00e9lais courts sur la base des fiches de donn\u00e9es de s\u00e9curit\u00e9 et nous \u00e9tablissons un bon plan pour l&#039;exp\u00e9dition des marchandises \u00e0 venir. En plus d&#039;un bon fret a\u00e9rien et maritime pour l&#039;exp\u00e9dition de marchandises dangereuses, XH fournit le meilleur service de camionnage et un bon prix.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c308bfc e-flex e-con-boxed e-con e-child\" data-id=\"c308bfc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a04b0e elementor-widget elementor-widget-button\" data-id=\"5a04b0e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/susi.xhddp.com\/fr\/obtenir-des-devis-pour-les-expeditions-de-la-chine-vers-le-monde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demandez un devis rapide<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79e968c elementor-widget elementor-widget-button\" data-id=\"79e968c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.me\/8618318063140\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">WhatsApp<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1c729 elementor-widget elementor-widget-video\" data-id=\"4c1c729\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/B-auwJNB25E&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/susi.xhddp.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/\\u6444\\u56fe\\u7f51_600275735_\\u56fd\\u9645\\u7269\\u6d41\\u4e2d\\u7684\\u8d27\\u8fd0\\u8239\\u975e\\u4f01\\u4e1a\\u5546\\u7528.jpg&quot;,&quot;id&quot;:3106,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/\u6444\u56fe\u7f51_600275735_\u56fd\u9645\u7269\u6d41\u4e2d\u7684\u8d27\u8fd0\u8239\u975e\u4f01\u4e1a\u5546\u7528.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Video abspielen\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-play\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M838 162C746 71 633 25 500 25 371 25 258 71 163 162 71 254 25 367 25 500 25 633 71 746 163 837 254 929 367 979 500 979 633 979 746 933 838 837 929 746 975 633 975 500 975 367 929 254 838 162M808 192C892 279 933 379 933 500 933 621 892 725 808 808 725 892 621 938 500 938 379 938 279 896 196 808 113 725 67 621 67 500 67 379 108 279 196 192 279 108 383 62 500 62 621 62 721 108 808 192M438 392V642L642 517 438 392Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-vitpkza e-flex e-con-boxed e-con e-parent\" data-id=\"vitpkza\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1eaf493 e-con-full e-flex e-con e-child\" data-id=\"1eaf493\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ea6a7d elementor-widget elementor-widget-heading\" data-id=\"2ea6a7d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Des canaux s\u00fbrs et rapides et des op\u00e9rations fiables garantissent l\u2019arriv\u00e9e en douceur des marchandises sensibles !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af052f elementor-widget elementor-widget-text-editor\" data-id=\"7af052f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous nous conformons aux r\u00e9glementations et proposons des op\u00e9rations logistiques professionnelles, des solutions de transport personnalis\u00e9es et des services de surveillance et de suivi en temps r\u00e9el. Nous nous engageons \u00e0 cr\u00e9er une plus grande valeur pour nos clients et \u00e0 assurer le transport s\u00fbr et efficace des marchandises sensibles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9k3aqt e-flex e-con-boxed e-con e-parent\" data-id=\"f9k3aqt\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9945606 e-con-full e-flex e-con e-child\" data-id=\"9945606\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c7a0f8 elementor-widget elementor-widget-image-box\" data-id=\"2c7a0f8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Nous pouvons transporter des marchandises sensibles telles que :<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe4d709 elementor-widget elementor-widget-text-editor\" data-id=\"fe4d709\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><ul><li><mark class=\"has-inline-color has-orange-color\">Pur\u00a0<\/mark><mark class=\"has-inline-color has-orange-color\">batterie<\/mark><mark class=\"has-inline-color has-orange-color\">\u00a0produits (surdimensionn\u00e9s <a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/service\/envoi-de-batteries-au-lithium-depuis-la-chine\/\"   title=\"piles\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"146\">piles<\/a>, Batteries OEM)<\/mark><\/li><li><mark class=\"has-inline-color has-orange-color\">Nourriture<\/mark><\/li><li><mark class=\"has-inline-color has-orange-color\">Produits liquides (dans les 300 millilitres)<\/mark><\/li><li><mark class=\"has-inline-color has-orange-color\">Produits de consolidation<\/mark><\/li><\/ul><\/div><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><ul><li><mark class=\"has-inline-color has-orange-color\">Produits \u00e9lectrifi\u00e9s (t\u00e9l\u00e9phones portables, montres, ordinateurs portables, \u00e9couteurs Bluetooth, v\u00e9hicule a\u00e9rien sans pilote)<\/mark><\/li><li><mark class=\"has-inline-color has-orange-color\">Produits de marque<\/mark><\/li><li><mark class=\"has-inline-color has-orange-color\">M\u00e9dicament<\/mark><\/li><\/ul><\/div><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><ul><li><mark class=\"has-inline-color has-orange-color\">V\u00e9hicules \u00e9lectriques (scooters, v\u00e9los \u00e9lectriques, tricycles \u00e9lectriques)<\/mark><\/li><li><mark class=\"has-inline-color has-orange-color\">Cosm\u00e9tique<\/mark><\/li><li><mark class=\"has-inline-color has-orange-color\">Chaussures et sacs<\/mark><\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f499284 e-con-full e-flex e-con e-child\" data-id=\"f499284\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25c13eb elementor-widget elementor-widget-image\" data-id=\"25c13eb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"905\" height=\"275\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d__1_-removebg-preview.png\" class=\"attachment-large size-large wp-image-3820\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d__1_-removebg-preview.png 905w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d__1_-removebg-preview-300x91.png 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d__1_-removebg-preview-768x233.png 768w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d__1_-removebg-preview-18x5.png 18w\" sizes=\"(max-width: 905px) 100vw, 905px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e78221 elementor-widget elementor-widget-image\" data-id=\"3e78221\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"270\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-2-1536x405-1-1024x270.png\" class=\"attachment-large size-large wp-image-3819\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-2-1536x405-1-1024x270.png 1024w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-2-1536x405-1-300x79.png 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-2-1536x405-1-768x203.png 768w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-2-1536x405-1-18x5.png 18w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-2-1536x405-1.png 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e5f574 elementor-widget elementor-widget-image\" data-id=\"0e5f574\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"333\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-3-1536x500-1-1024x333.png\" class=\"attachment-large size-large wp-image-3818\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-3-1536x500-1-1024x333.png 1024w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-3-1536x500-1-300x98.png 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-3-1536x500-1-768x250.png 768w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-3-1536x500-1-18x6.png 18w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u4e0b\u8f7d-3-1536x500-1.png 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53955cd e-flex e-con-boxed e-con e-parent\" data-id=\"53955cd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14e1ef1 elementor-widget elementor-widget-ucaddon_content_grid2\" data-id=\"14e1ef1\" data-element_type=\"widget\" data-widget_type=\"ucaddon_content_grid2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Content Grid -->\n\t\t<link id='font-awesome-css' href='https:\/\/susi.xhddp.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/susi.xhddp.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome5\/css\/fontawesome-v4-shims.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='fancybox-css' href='https:\/\/susi.xhddp.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/fancybox3\/jquery.fancybox.min.css' type='text\/css' rel='stylesheet' >\n\n\t\t\t<style type=\"text\/css\">\/* widget: Content Grid *\/\n\n\t\t\t\r\n@keyframes uc_content_grid2_elementor_14e1ef1__item-animation {\r\n  0% {\r\n            transform:scale(0.7);        \t\r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\t\t\t        \t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            transform:scale(1);            \r\n        \t            filter: blur(0px);\r\n                        \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\t\t\t\r\n\t\t\t\r\n#uc_content_grid2_elementor_14e1ef1 .ue-item{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_content_grid2_elementor_14e1ef1 .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_content_grid2_elementor_14e1ef1 .uc-entrance-animate {\r\n\tanimation: uc_content_grid2_elementor_14e1ef1__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_content_grid2_elementor_14e1ef1 * {\n\tbox-sizing: border-box;\t\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_wrap {\n\tdisplay: grid;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_image {\n\twidth: 100%;\n\toverflow: hidden;\n\tdisplay: block;  \t\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_image {\n\twidth: inherit;\n\theight: inherit;\n\tbackground-position: center center;\n\tbackground-repeat: no-repeat;\n\tdisplay: block;\n\ttransition: all 0.25s ease-in-out;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .ue-image-holder a{\n  display:block;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .ue-item{\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .ue-item-title{\n  width:100%;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .ue-item-text{\n  width:100%;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_content{\n  display:flex;\n  flex-direction:column;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .ue-content-wrapper{\n  width:100%;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .ue-button{\n  margin-top:auto;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .ue-button{\n  width:100%;\n}\n\n\n\t#uc_content_grid2_elementor_14e1ef1.uc_post_grid_style_one .uc_content{\n      position:absolute;\n      top:0px;\n      left:0px;\n      bottom:0px;\n      right:0px;\n      opacity:0;\n      transition:1s;\n      display:flex;\n      align-items:center;\n      flex-direction:column;\n      justify-content: center;\n    }\n\n\t#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_item:hover .uc_content{\n      opacity:1;\n    }\n\n\n\n\n\n\n\n#uc_content_grid2_elementor_14e1ef1.uc-remote-parent .ue-item{\n  cursor:pointer;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_search_wrap{\n  display: flex;  \n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_search_container{\n  position: relative;\n}\n\n\n#uc_content_grid2_elementor_14e1ef1 ::-webkit-input-placeholder { \/* Edge *\/\n  color: #8f8f8f;\n}\n\n#uc_content_grid2_elementor_14e1ef1 :-ms-input-placeholder { \/* Internet Explorer 10-11 *\/\n  color: #8f8f8f;\n}\n\n#uc_content_grid2_elementor_14e1ef1 ::placeholder {\n  color: #8f8f8f;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_next_button_pagination_button{\n      display: none;\n  }\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_search_icon,\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_reset_icon{\n\tposition: absolute;\n  \ttop: 50%;\n    transform: translate(0, -50%);\n    height: 100%;\n  \tdisplay: flex;\n    align-items: center;\n    justify-content: center;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_reset_icon{\n  cursor: pointer;\n}\n\n\n\/* pagination *\/\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_prev_button_pagination{\n  display: flex;\n  align-items: center;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_pagination_button,\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_pagination_number{\n  padding: 0;\n  justify-content: center;\n  align-items: center;\n  transition: all .3s ease;\n  margin: 0;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_pagination_number:last-child,\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_pagination_number:first-child{\n  display: inline-flex;\n  position: relative;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .ue-hidden{\n  display: none;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .ue-disabled{\n  opacity: .5;\n  pointer-events: none;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_pagination_number.ue-visible{\n  display: inline-flex;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_pagination_numbers{\n  display: flex;\n  flex-wrap: wrap;\n}\n\n#uc_content_grid2_elementor_14e1ef1 .uc_post_grid_style_one_prev_button_pagination_wrap{\n  display: flex;\n}\n\/* end pagination *\/\n\n<\/style>\n\n\t\t\t<div id=\"uc_content_grid2_elementor_14e1ef1\" class=\"uc_post_grid_style_one uc_items\"   data-lightbox=\"false\">\n  \n    \n  <div class=\"uc_post_grid_style_one_wrap uc-items-wrapper\">\n          \n<div class=\"uc_post_grid_style_one_item ue-item\">\n    \n      <div class=\"uc_post_grid_style_one_image ue-image-holder\">\n                \n    <div aria-role=\"img\" aria-label=\"\u5fae\u4fe1\u56fe\u7247_20220813111045-1024x768\"  class=\"uc_post_image\" style=\"background-image: url(https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u5fae\u4fe1\u56fe\u7247_20220813111045-1024x768-1-768x576.webp);\"><\/div>\n        <\/div>\n    \n  <div class=\"uc_content padding\">\n    <div class=\"ue-content-wrapper\">\n      \n            \n            \n            \n    <\/div>\n    \n        \n  <\/div>\n<\/div>\n\n<div class=\"uc_post_grid_style_one_item ue-item\">\n    \n      <div class=\"uc_post_grid_style_one_image ue-image-holder\">\n                \n    <div aria-role=\"img\" aria-label=\"\u5fae\u4fe1\u56fe\u7247_20220813111128-1024x768\"  class=\"uc_post_image\" style=\"background-image: url(https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u5fae\u4fe1\u56fe\u7247_20220813111128-1024x768-1-768x576.webp);\"><\/div>\n        <\/div>\n    \n  <div class=\"uc_content padding\">\n    <div class=\"ue-content-wrapper\">\n      \n            \n            \n            \n    <\/div>\n    \n        \n  <\/div>\n<\/div>\n\n<div class=\"uc_post_grid_style_one_item ue-item\">\n    \n      <div class=\"uc_post_grid_style_one_image ue-image-holder\">\n                \n    <div aria-role=\"img\" aria-label=\"\u5fae\u4fe1\u56fe\u7247_20220813111405-1-1024x768\"  class=\"uc_post_image\" style=\"background-image: url(https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u5fae\u4fe1\u56fe\u7247_20220813111405-1-1024x768-1-768x576.webp);\"><\/div>\n        <\/div>\n    \n  <div class=\"uc_content padding\">\n    <div class=\"ue-content-wrapper\">\n      \n            \n            \n            \n    <\/div>\n    \n        \n  <\/div>\n<\/div>\n\n<div class=\"uc_post_grid_style_one_item ue-item\">\n    \n      <div class=\"uc_post_grid_style_one_image ue-image-holder\">\n                \n    <div aria-role=\"img\" aria-label=\"\u5fae\u4fe1\u56fe\u7247_20220813110134-1024x768\"  class=\"uc_post_image\" style=\"background-image: url(https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u5fae\u4fe1\u56fe\u7247_20220813110134-1024x768-1-768x576.webp);\"><\/div>\n        <\/div>\n    \n  <div class=\"uc_content padding\">\n    <div class=\"ue-content-wrapper\">\n      \n            \n            \n            \n    <\/div>\n    \n        \n  <\/div>\n<\/div>\n\n<div class=\"uc_post_grid_style_one_item ue-item\">\n    \n      <div class=\"uc_post_grid_style_one_image ue-image-holder\">\n                \n    <div aria-role=\"img\" aria-label=\"\u5fae\u4fe1\u56fe\u7247_20220813111357-1024x768\"  class=\"uc_post_image\" style=\"background-image: url(https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u5fae\u4fe1\u56fe\u7247_20220813111357-1024x768-1-768x576.webp);\"><\/div>\n        <\/div>\n    \n  <div class=\"uc_content padding\">\n    <div class=\"ue-content-wrapper\">\n      \n            \n            \n            \n    <\/div>\n    \n        \n  <\/div>\n<\/div>\n\n<div class=\"uc_post_grid_style_one_item ue-item\">\n    \n      <div class=\"uc_post_grid_style_one_image ue-image-holder\">\n                \n    <div aria-role=\"img\" aria-label=\"\u5fae\u4fe1\u56fe\u7247_20220813111221-1024x768\"  class=\"uc_post_image\" style=\"background-image: url(https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/12\/\u5fae\u4fe1\u56fe\u7247_20220813111221-1024x768-1-768x576.webp);\"><\/div>\n        <\/div>\n    \n  <div class=\"uc_content padding\">\n    <div class=\"ue-content-wrapper\">\n      \n            \n            \n            \n    <\/div>\n    \n        \n  <\/div>\n<\/div>\n\n      <\/div>  \n    \n<\/div>\n\t\t\t<!-- end Content Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b69f2e e-flex e-con-boxed e-con e-parent\" data-id=\"6b69f2e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2b1fa4 elementor-widget elementor-widget-spacer\" data-id=\"e2b1fa4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63c202f elementor-widget elementor-widget-heading\" data-id=\"63c202f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quels types de m\u00e9thodes d&#039;exp\u00e9dition de porte \u00e0 porte existe-t-il ?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1df4add elementor-widget elementor-widget-text-editor\" data-id=\"1df4add\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les principales m\u00e9thodes d&#039;exp\u00e9dition internationales de la Chine vers d&#039;autres pays comprennent <a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/service\/fret-express-depuis-la-chine\/\"   title=\"Fret express\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"100\">Fret express<\/a>Fret a\u00e9rien, fret maritime, fret ferroviaire vers certains pays europ\u00e9ens et fret routier par camion. Exp\u00e9dition porte-\u00e0-porte de la Chine vers <a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/service\/chine-vers-amazon-fba\/\"   title=\"Exp\u00e9di\u00e9 par Amazon\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"132\">Exp\u00e9di\u00e9 par Amazon<\/a>.<\/p><p>Les m\u00e9thodes d&#039;exp\u00e9dition de porte \u00e0 porte sont combin\u00e9es par eux. Il existe donc au moins 7 types de <a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/service\/expedition-porte-a-porte-depuis-la-chine\/\"   title=\"Porte \u00e0 porte\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"130\">Porte \u00e0 porte<\/a> M\u00e9thodes d&#039;exp\u00e9dition que nous pouvons proposer pour votre choix.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-reupxvm e-flex e-con-boxed e-con e-parent\" data-id=\"reupxvm\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ad51ed6 e-con-full e-flex e-con e-child\" data-id=\"ad51ed6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd3e65d elementor-widget elementor-widget-image\" data-id=\"cd3e65d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"329\" height=\"153\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/images-8.png\" class=\"attachment-large size-large wp-image-3558\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/images-8.png 329w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/images-8-300x140.png 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/images-8-18x8.png 18w\" sizes=\"(max-width: 329px) 100vw, 329px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b18acd9 e-con-full e-flex e-con e-child\" data-id=\"b18acd9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e058d6e elementor-widget elementor-widget-heading\" data-id=\"e058d6e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Fret express porte \u00e0 porte depuis la Chine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4520ec3 elementor-widget elementor-widget-text-editor\" data-id=\"4520ec3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ils sont:<\/p><p>Exp\u00e9dition porte \u00e0 porte DHL.<br \/>Exp\u00e9dition porte \u00e0 porte UPS<br \/>Exp\u00e9dition porte \u00e0 porte TNT.<br \/>Exp\u00e9dition porte \u00e0 porte FedEx.<br \/>Exp\u00e9dition express porte \u00e0 porte SF.<\/p><p>Il s&#039;agit d&#039;une exp\u00e9dition par fret express tout au long de la progression de l&#039;exp\u00e9dition depuis l&#039;usine de vos fournisseurs chinois jusqu&#039;\u00e0 l&#039;adresse de destination selon les besoins.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-lzdnyqm e-flex e-con-boxed e-con e-parent\" data-id=\"lzdnyqm\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9945606 e-con-full e-flex e-con e-child\" data-id=\"9945606\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c7a0f8 elementor-widget elementor-widget-image-box\" data-id=\"2c7a0f8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">2. Fret a\u00e9rien combin\u00e9 avec fret express depuis la Chine<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe4d709 elementor-widget elementor-widget-text-editor\" data-id=\"fe4d709\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il s&#039;agit d&#039;une m\u00e9thode d&#039;exp\u00e9dition de la Chine vers le pays de destination par les lignes a\u00e9riennes courantes. Une fois les marchandises arriv\u00e9es \u00e0 l&#039;a\u00e9roport de destination et la d\u00e9claration douani\u00e8re d&#039;entr\u00e9e termin\u00e9e, elles seront livr\u00e9es \u00e0 votre adresse de destination finale par une soci\u00e9t\u00e9 express comme DHL UPS FEDEX.<\/p><p>Cette m\u00e9thode est g\u00e9n\u00e9ralement destin\u00e9e aux colis courants. \u00c9tant donn\u00e9 le grand nombre de colis surdimensionn\u00e9s, il existe de meilleures m\u00e9thodes d&#039;exp\u00e9dition que celles que je vais vous pr\u00e9senter ci-dessous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f499284 e-con-full e-flex e-con e-child\" data-id=\"f499284\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12d7e03 elementor-widget elementor-widget-image\" data-id=\"12d7e03\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/replace\/2024\/11\/29\/904331b8533c87183efd7ac57fa3cf2a.webp\" class=\"attachment-large size-large wp-image-3495\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e0cef0 e-flex e-con-boxed e-con e-parent\" data-id=\"4e0cef0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0951985 e-con-full e-flex e-con e-child\" data-id=\"0951985\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b49e7e elementor-widget elementor-widget-image-box\" data-id=\"2b49e7e\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Quels documents faut-il fournir pour la m\u00e9thode d&#039;exp\u00e9dition porte \u00e0 porte ?<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b896ab elementor-widget elementor-widget-text-editor\" data-id=\"7b896ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les m\u00e9thodes d&#039;exp\u00e9dition de porte \u00e0 porte depuis la Chine sont bas\u00e9es sur les m\u00e9thodes d&#039;exp\u00e9dition courantes. Donc, si vous coop\u00e9rez avec nous, il vous suffit de fournir les<br \/>1. Facture commerciale<br \/>2. Liste de colisage<br \/>3. Certificat d&#039;origine (certains pays n&#039;en ont pas besoin).<br \/>4. Certificat de produits comme CE. FCC.FDA (les fournisseurs doivent l&#039;avoir.)<\/p><p>Ensuite, nous pouvons vous aider \u00e0 organiser tous les autres. C&#039;est une chose tr\u00e8s simple.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f0ddcf9 e-con-full e-flex e-con e-child\" data-id=\"f0ddcf9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d35cfad elementor-widget elementor-widget-image\" data-id=\"d35cfad\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/349814890-1024x678.webp\" class=\"attachment-large size-large wp-image-3555\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/349814890-1024x678.webp 1024w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/349814890-300x199.webp 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/349814890-768x509.webp 768w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/349814890-18x12.webp 18w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/349814890.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc9db25 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cc9db25\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/susi.xhddp.com\/fr\/obtenir-des-devis-pour-les-expeditions-de-la-chine-vers-le-monde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demandez un devis rapide<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4aa55ed e-flex e-con-boxed e-con e-parent\" data-id=\"4aa55ed\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e6b57a e-con-full e-flex e-con e-child\" data-id=\"6e6b57a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2554d9f elementor-widget elementor-widget-image\" data-id=\"2554d9f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"412\" height=\"262\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/door-to-door-delivery-time.webp\" class=\"attachment-large size-large wp-image-3778\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/door-to-door-delivery-time.webp 412w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/door-to-door-delivery-time-300x191.webp 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/door-to-door-delivery-time-18x12.webp 18w\" sizes=\"(max-width: 412px) 100vw, 412px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d740d93 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d740d93\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/susi.xhddp.com\/fr\/obtenir-des-devis-pour-les-expeditions-de-la-chine-vers-le-monde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demandez un devis rapide<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-531ffa2 e-con-full e-flex e-con e-child\" data-id=\"531ffa2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60a4e4f elementor-widget elementor-widget-image-box\" data-id=\"60a4e4f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">D\u00e9lai d&#039;exp\u00e9dition pour une livraison porte \u00e0 porte depuis la Chine<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9ac09d elementor-widget elementor-widget-text-editor\" data-id=\"d9ac09d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le d\u00e9lai d&#039;exp\u00e9dition porte \u00e0 porte de la Chine vers l&#039;\u00e9tranger d\u00e9pend du pays de destination et des outils de transit que nous choisissons. Le d\u00e9lai d&#039;exp\u00e9dition approximatif peut \u00eatre fourni \u00e0 titre indicatif uniquement.<\/p><p>1. Le fret express porte \u00e0 porte depuis la Chine prend environ 3 \u00e0 7 jours\u00a0;<br \/>2. <a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/service\/fret-aerien-en-provenance-de-chine\/\"   title=\"Fret a\u00e9rien\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"145\">Fret a\u00e9rien<\/a> combin\u00e9 avec le fret express depuis la Chine, le d\u00e9lai est d&#039;environ 5 \u00e0 7 jours.<br \/>3. Le fret a\u00e9rien combin\u00e9 au fret routier depuis la Chine prend environ 7 \u00e0 12 jours ;<br \/>4. <a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/service\/fret-maritime-depuis-la-chine\/\"   title=\"Oc\u00e9an\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"143\">Oc\u00e9an<\/a> le fret combin\u00e9 avec le fret express depuis la Chine prend environ 20 \u00e0 30 jours\u00a0;<br \/>5. Le fret maritime combin\u00e9 au fret routier depuis la Chine prend environ 25 \u00e0 45 jours\u00a0;<br \/>6. <a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/service\/fret-ferroviaire-en-provenance-de-chine\/\"   title=\"Fret ferroviaire\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"128\">Fret ferroviaire<\/a> combin\u00e9 avec le fret express depuis la Chine, le d\u00e9lai est d&#039;environ 30 \u00e0 40 jours\u00a0;<br \/>7. Le fret ferroviaire combin\u00e9 au fret routier en provenance de Chine prend environ 35 \u00e0 45 jours.<\/p><p>Ce \u00e0 quoi vous devez faire attention, c&#039;est qu&#039;il ne s&#039;agit que d&#039;un d\u00e9lai d&#039;exp\u00e9dition approximatif \u00e0 titre de r\u00e9f\u00e9rence, mais si vous avez besoin d&#039;une heure d&#039;arriv\u00e9e exacte, vous devez alors vous renseigner sur les d\u00e9tails de chaque exp\u00e9dition. En raison du fait que les pays sont diff\u00e9rents de la Chine, le temps est tr\u00e8s diff\u00e9rent. Par exemple, le fret maritime le plus rapide de la Chine vers les \u00c9tats-Unis prend 12 jours. Le fret a\u00e9rien le plus rapide de la Chine vers les \u00c9tats-Unis peut arriver en 2 jours. Ainsi, lorsque vous nous demandez combien de temps prend le transport porte \u00e0 porte depuis la Chine, vous devez nous envoyer tous les d\u00e9tails, y compris l&#039;adresse de prise en charge en Chine et l&#039;adresse d&#039;exp\u00e9dition dans le<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a9296a e-flex e-con-boxed e-con e-parent\" data-id=\"3a9296a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9d1e661 e-con-full e-flex e-con e-child\" data-id=\"9d1e661\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cfb61a elementor-widget elementor-widget-image-box\" data-id=\"2cfb61a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Quels types de marchandises ne peuvent pas \u00eatre exp\u00e9di\u00e9es par des m\u00e9thodes d&#039;exp\u00e9dition porte \u00e0 porte depuis la Chine ?<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96a8a84 elementor-widget elementor-widget-text-editor\" data-id=\"96a8a84\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La logistique internationale est aujourd&#039;hui un secteur de plus en plus mature et, avant 2014, l&#039;int\u00e9gration des ressources n&#039;\u00e9tait peut-\u00eatre pas aussi compl\u00e8te qu&#039;aujourd&#039;hui. Aujourd&#039;hui, en 2022, les transitaires qualifi\u00e9s sont en mesure de fournir des services de transport de porte \u00e0 porte.<\/p><p>Nos services porte-\u00e0-porte XH vers les \u00c9tats-Unis et les pays europ\u00e9ens fonctionnent tr\u00e8s bien.<\/p><p>Nous disposons de plusieurs itin\u00e9raires porte-\u00e0-porte avec 30 \u00e0 50 tonnes de marchandises en provenance de Chine par jour.<\/p><p><a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/contact\/\"   title=\"Contactez-nous\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"314\">Contactez-nous<\/a> d\u00e8s maintenant pour un devis rapide.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7e1ccd e-con-full e-flex e-con e-child\" data-id=\"d7e1ccd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f527dc3 elementor-widget elementor-widget-image\" data-id=\"f527dc3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/465839636_1093316919163311_6852845963978714265_n.jpg\" class=\"attachment-large size-large wp-image-3222\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/465839636_1093316919163311_6852845963978714265_n.jpg 720w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/465839636_1093316919163311_6852845963978714265_n-300x300.jpg 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/465839636_1093316919163311_6852845963978714265_n-150x150.jpg 150w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/465839636_1093316919163311_6852845963978714265_n-12x12.jpg 12w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6519688 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6519688\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/susi.xhddp.com\/fr\/obtenir-des-devis-pour-les-expeditions-de-la-chine-vers-le-monde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demandez un devis rapide<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78a8162 e-flex e-con-boxed e-con e-parent\" data-id=\"78a8162\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-87c09df e-con-full e-flex e-con e-child\" data-id=\"87c09df\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-415757b elementor-widget elementor-widget-image\" data-id=\"415757b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/depositphotos_442641776-stock-photo-world-logistics-background-transportation-industry.webp\" class=\"attachment-large size-large wp-image-3753\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/depositphotos_442641776-stock-photo-world-logistics-background-transportation-industry.webp 600w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/depositphotos_442641776-stock-photo-world-logistics-background-transportation-industry-300x200.webp 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/depositphotos_442641776-stock-photo-world-logistics-background-transportation-industry-18x12.webp 18w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bac70b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9bac70b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/susi.xhddp.com\/fr\/obtenir-des-devis-pour-les-expeditions-de-la-chine-vers-le-monde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demandez un devis rapide<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae424da e-con-full e-flex e-con e-child\" data-id=\"ae424da\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6045516 elementor-widget elementor-widget-image-box\" data-id=\"6045516\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Comment choisir un transitaire de transport porte-\u00e0-porte depuis la Chine ?<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c22bda elementor-widget elementor-widget-text-editor\" data-id=\"1c22bda\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avant de d\u00e9cider de coop\u00e9rer avec un transitaire chinois, voici les \u00e9l\u00e9ments de base que vous devez confirmer concernant le transitaire :<br \/>1. Le transitaire chinois doit disposer d&#039;une licence commerciale l\u00e9gitime.<br \/>2. Doit avoir la possibilit\u00e9 de r\u00e9cup\u00e9rer les envois pour vous en Chine continentale dans n&#039;importe quelle ville.<br \/>3. Vous devez avoir la capacit\u00e9 d&#039;effectuer le nettoyage douanier pour tous vos envois.<br \/>4. Vous devez disposer d\u2019un entrep\u00f4t suffisamment grand pour stocker vos envois.<br \/>5. Vous devez proposer des prix comp\u00e9titifs pour vos envois. Vous n&#039;avez pas besoin du moins cher, mais vous devez proposer le prix le plus comp\u00e9titif.<br \/>6. Doit avoir au moins 5 ans ou plus d&#039;exp\u00e9rience dans l&#039;exp\u00e9dition depuis la Chine. (Pour ce point, vous saurez que coop\u00e9rer avec un transitaire exp\u00e9riment\u00e9 peut vous aider \u00e0 \u00e9conomiser beaucoup.)<br \/>7. Doit avoir diff\u00e9rentes m\u00e9thodes d&#039;exp\u00e9dition pour r\u00e9pondre \u00e0 vos diff\u00e9rentes exigences d&#039;exp\u00e9dition.<br \/>8. Plus votre transitaire peut fournir de ressources, mieux vous pourrez coop\u00e9rer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d23b39 e-con-full e-flex e-con e-parent\" data-id=\"6d23b39\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff3851 elementor-widget elementor-widget-heading\" data-id=\"2ff3851\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ sur l&#039;exp\u00e9dition porte \u00e0 porte depuis la Chine.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32a11ee e-con-full e-flex e-con e-child\" data-id=\"32a11ee\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0e641f elementor-widget__width-inherit elementor-widget elementor-widget-toggle\" data-id=\"e0e641f\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2351\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2351\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mes marchandises seront-elles factur\u00e9es de mani\u00e8re d\u00e9raisonnable apr\u00e8s leur arriv\u00e9e dans votre entrep\u00f4t ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2351\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2351\"><p>Non, nous souhaitons une coop\u00e9ration stable \u00e0 long terme, serons honn\u00eates pour le prix unitaire et n&#039;aurons pas de frais cach\u00e9s apr\u00e8s avoir r\u00e9cup\u00e9r\u00e9 vos marchandises. Tous les co\u00fbts seront clairement indiqu\u00e9s avant que nous acceptions de coop\u00e9rer les uns avec les autres.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2352\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2352\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mes marchandises seront-elles transf\u00e9r\u00e9es vers un canal de transport moins cher une fois le paiement effectu\u00e9 ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2352\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2352\"><p>Non, nous organiserons la m\u00e9thode d&#039;exp\u00e9dition en fonction de ce que nous avons indiqu\u00e9. Nous souhaitons uniquement une coop\u00e9ration \u00e0 long terme avec vous. Il n&#039;est donc pas n\u00e9cessaire de nous tromper.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2353\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2353\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pouvez-vous m&#039;aider \u00e0 reconditionner mes cartons et \u00e0 changer l&#039;\u00e9tiquette ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2353\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2353\"><p>Oui, c&#039;est l&#039;un de nos basiques <a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/service\/\"   title=\"service\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"144\">service<\/a>.nous serons heureux de vous aider \u00e0 y parvenir.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2354\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2354\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Combien facturez-vous pour changer l&#039;\u00e9tiquette et reconditionner les marchandises ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2354\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2354\"><p>Comme d&#039;habitude, c&#039;est gratuit. Mais si le travail n\u00e9cessite beaucoup de personnel et beaucoup de temps, nous pourrons alors discuter des d\u00e9tails avant de continuer.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2355\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2355\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle est votre couverture de devis ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2355\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2355\"><p>Notre devis des m\u00e9thodes d&#039;exp\u00e9dition DDP, y compris vos taxes d&#039;importation, vous aidera \u00e0 organiser la d\u00e9claration douani\u00e8re des deux c\u00f4t\u00e9s et elles sont livr\u00e9es \u00e0 domicile. Le devis des m\u00e9thodes d&#039;exp\u00e9dition DDU est livr\u00e9 \u00e0 domicile mais n&#039;inclut pas les taxes.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2356\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2356\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pouvez-vous proposer un service de ramassage ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2356\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2356\"><p>Oui, bien s\u00fbr, nous pouvons vous aider \u00e0 r\u00e9cup\u00e9rer vos marchandises dans n&#039;importe quelle ville en Chine. Nous disposons d\u00e9j\u00e0 de nombreuses cha\u00eenes d&#039;approvisionnement matures qui peuvent certainement r\u00e9pondre \u00e0 tout type d&#039;exigences de ramassage, qu&#039;il s&#039;agisse d&#039;exp\u00e9dition par conteneur ou de petits colis courants.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2357\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2357\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Allez-vous ajouter le poids de la charge \u00e0 la r\u00e9ception des produits ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2357\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2357\"><p>Nous serons honn\u00eates pour prendre le poids et mesurer avec la norme logistique. Nous tenons \u00e0 une coop\u00e9ration \u00e0 long terme et non pas une seule fois. En attendant, vous pouvez mesurer et peser les produits apr\u00e8s r\u00e9ception des marchandises pour v\u00e9rifier le poids de la charge.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2358\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2358\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel est le meilleur moyen d&#039;exp\u00e9dier de la Chine vers les \u00c9tats-Unis ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2358\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2358\"><p>Cela d\u00e9pend de vos exigences d\u00e9taill\u00e9es et des informations d\u00e9taill\u00e9es sur les exp\u00e9ditions. Apr\u00e8s avoir obtenu les d\u00e9tails de votre part, nous pouvons faire une offre pour votre choix.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-2359\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2359\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quand devons-nous payer, avant ou apr\u00e8s avoir re\u00e7u les marchandises ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2359\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2359\"><p>Une fois que tout est confirm\u00e9 sans probl\u00e8me, nous vous fournirons la facture pro forma des frais d&#039;exp\u00e9dition et vous enverrons le num\u00e9ro de suivi en ligne. Vous payez ensuite.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-23510\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-23510\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment puis-je vous payer ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-23510\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-23510\">Nous avons une vari\u00e9t\u00e9 de m\u00e9thodes de paiement, veuillez contacter le service client pour plus de d\u00e9tails.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af1fcd elementor-widget__width-inherit elementor-widget elementor-widget-toggle\" data-id=\"7af1fcd\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1281\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1281\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Allez-vous augmenter le prix apr\u00e8s avoir re\u00e7u mes produits ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1281\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1281\">Si la plupart des gens savent que la compagnie a\u00e9rienne\/maritime augmente le prix du bateau, nous augmenterons le prix en cons\u00e9quence. Mais nous n&#039;augmenterons pas sans raison. Peut-\u00eatre que nous n&#039;augmenterons pas ou seulement un peu, car les affaires \u00e0 long terme peuvent nous fournir une relation de coop\u00e9ration gagnant-gagnant.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1282\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1282\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Combien de temps pouvons-nous recevoir apr\u00e8s votre exp\u00e9dition ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1282\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1282\">Les m\u00e9thodes de transport maritime prennent environ 18 \u00e0 25 jours ; les m\u00e9thodes de transport a\u00e9rien prennent environ 5 \u00e0 7 jours ouvrables ; les m\u00e9thodes express prennent environ 3 \u00e0 5 jours ouvrables. Pour plus de d\u00e9tails, nous pouvons vous proposer un devis apr\u00e8s avoir re\u00e7u vos exigences.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1283\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1283\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment faire un envoi ? Doit-on ouvrir un compte ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1283\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1283\">Non, vous n&#039;avez pas besoin d&#039;ouvrir un compte chez nous. Vous pouvez d&#039;abord laisser votre fournisseur exp\u00e9dier les marchandises \u00e0 notre entrep\u00f4t. D\u00e8s r\u00e9ception, nous confirmerons le poids, la taille, prendrons des photos et vous indiquerons le prix. Apr\u00e8s tout, nous confirmerons sans probl\u00e8me, puis nous vous exp\u00e9dierons.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1284\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1284\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mon fournisseur n&#039;a pas le droit d&#039;exporter, pouvez-vous m&#039;aider \u00e0 exporter les marchandises depuis la Chine ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1284\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1284\">Oui, nous pouvons, nous vous aiderons \u00e0 acheter la licence d&#039;exportation, \u00e0 faire la d\u00e9claration en douane et \u00e0 vous exp\u00e9dier les marchandises.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1285\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1285\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pouvez-vous aider \u00e0 collecter aupr\u00e8s de diff\u00e9rents fournisseurs et \u00e0 exp\u00e9dier ensemble ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1285\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1285\">Oui, nous pouvons venir chercher n&#039;importe quelle marchandise en Chine continentale, la stocker dans notre entrep\u00f4t pour vous et l&#039;exp\u00e9dier en une seule fois une fois toutes les marchandises des fournisseurs termin\u00e9es.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1286\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1286\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment suivre mes envois ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1286\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1286\">Nous vous enverrons un num\u00e9ro de suivi une fois que nous aurons envoy\u00e9 la cargaison au transporteur. Ensuite, vous pourrez suivre en ligne. Nous vous enverrons \u00e9galement un rapport de suivi.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1287\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1287\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment commencer \u00e0 coop\u00e9rer avec vous ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1287\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1287\">Envoyez-nous simplement une demande. Veuillez nous communiquer les informations sur votre produit et nous faire part de vos exigences en mati\u00e8re d&#039;exp\u00e9dition. Nous pourrons ensuite \u00e9tablir un devis et commencer \u00e0 organiser l&#039;exp\u00e9dition pour vous.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1288\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1288\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pouvez-vous m\u2019aider \u00e0 souscrire une assurance ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1288\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1288\">Bien s\u00fbr. Pour les produits \u00e0 forte valeur commerciale, nous recommandons de souscrire une assurance. Nous pouvons vous aider \u00e0 souscrire car nous pouvons obtenir un prix bien inf\u00e9rieur \u00e0 celui que vous auriez vous-m\u00eame pay\u00e9, puisque nous achetons chaque jour des produits diff\u00e9rents pour diff\u00e9rents clients. Nous b\u00e9n\u00e9ficions donc de bonnes remises sur notre cha\u00eene d&#039;approvisionnement.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1289\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1289\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">De quoi ai-je besoin pour obtenir un devis pr\u00e9cis ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1289\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1289\">Vous devez nous envoyer le nom de la marchandise, la liste d&#039;emballage de la marchandise, l&#039;adresse de retrait en Chine, l&#039;adresse de destination, le d\u00e9lai d&#039;exp\u00e9dition requis, la marchandise avec batterie ou non, la date \u00e0 laquelle la marchandise peut \u00eatre pr\u00eate. Apr\u00e8s avoir obtenu toutes les informations ci-dessus, nous vous ferons un devis exactement dans les 10 minutes.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-12810\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-12810\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a1e64e0c-4c41-4fca-8542-7a49c6092caa\" data-name=\"Layer 1\" width=\"16.9661\" height=\"16.9661\" viewbox=\"0 0 16.9661 16.9661\"><defs><style>.aed1427e-e5ff-4359-b373-334313c48315{fill:#1c2448;}<\/style><\/defs><path class=\"aed1427e-e5ff-4359-b373-334313c48315\" d=\"M8.8969,16.966V8.9071h8.0692V8.1012H8.8969V0H8.0693V8.1012H0v.8059H8.0693V16.966Z\" transform=\"translate(0 0.0001)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"ef88faed-b140-41a0-9417-c1651f3bd4fc\" data-name=\"Layer 1\" width=\"13.785\" height=\"1.0074\" viewbox=\"0 0 13.785 1.0074\"><defs><style>.e3c7dd86-9752-467e-8574-885a4e9461bb{fill:#1c2448;}<\/style><\/defs><path class=\"e3c7dd86-9752-467e-8574-885a4e9461bb\" d=\"M13.785,1.0338V.0265H0V1.0338Z\" transform=\"translate(0 -0.0265)\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle m\u00e9thode d&#039;exp\u00e9dition est la meilleure ?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-12810\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-12810\">Cela d\u00e9pend de vos exigences en mati\u00e8re de d\u00e9lai d&#039;exp\u00e9dition, du poids des marchandises et de votre budget d&#039;exp\u00e9dition. Envoyez-nous vos informations et nous vous fournirons au moins 3 \u00e0 4 m\u00e9thodes pour chacune de vos exp\u00e9ditions.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d99deb5 elementor-widget elementor-widget-spacer\" data-id=\"d99deb5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45302a4a e-flex e-con-boxed e-con e-parent\" data-id=\"45302a4a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8381244 e-con-full e-flex e-con e-child\" data-id=\"8381244\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1346e94f animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1346e94f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Exp\u00e9diez depuis la Chine vers n&#039;importe quel endroit de votre choix<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bae90 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"1bae90\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-grow\" href=\"https:\/\/susi.xhddp.com\/fr\/obtenir-des-devis-pour-les-expeditions-de-la-chine-vers-le-monde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demandez un devis rapide<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52e13408 e-con-full e-flex e-con e-child\" data-id=\"52e13408\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4176a5f3 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4176a5f3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"594\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/5db188fa836b442786ccfbb9c6292c62-1024x594.webp\" class=\"attachment-large size-large wp-image-2372\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/5db188fa836b442786ccfbb9c6292c62-1024x594.webp 1024w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/5db188fa836b442786ccfbb9c6292c62-300x174.webp 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/5db188fa836b442786ccfbb9c6292c62-768x445.webp 768w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/5db188fa836b442786ccfbb9c6292c62-1536x891.webp 1536w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/5db188fa836b442786ccfbb9c6292c62-2048x1188.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14dd7de6 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"14dd7de6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/\u6444\u56fe\u7f51_600483754_\u8fdc\u6d0b\u7684\u8d27\u8f6e\u975e\u4f01\u4e1a\u5546\u7528-1024x574.jpg\" class=\"attachment-large size-large wp-image-2356\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/\u6444\u56fe\u7f51_600483754_\u8fdc\u6d0b\u7684\u8d27\u8f6e\u975e\u4f01\u4e1a\u5546\u7528-1024x574.jpg 1024w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/\u6444\u56fe\u7f51_600483754_\u8fdc\u6d0b\u7684\u8d27\u8f6e\u975e\u4f01\u4e1a\u5546\u7528-300x168.jpg 300w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/\u6444\u56fe\u7f51_600483754_\u8fdc\u6d0b\u7684\u8d27\u8f6e\u975e\u4f01\u4e1a\u5546\u7528-768x430.jpg 768w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/\u6444\u56fe\u7f51_600483754_\u8fdc\u6d0b\u7684\u8d27\u8f6e\u975e\u4f01\u4e1a\u5546\u7528.jpg 1456w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c72537b e-flex e-con-boxed e-con e-parent\" data-id=\"c72537b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d8186e elementor-widget elementor-widget-spacer\" data-id=\"8d8186e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2f03a0 e-flex e-con-boxed e-con e-parent\" data-id=\"b2f03a0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad92bb7 elementor-widget elementor-widget-spacer\" data-id=\"ad92bb7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ca936a elementor-widget elementor-widget-heading\" data-id=\"6ca936a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos utilisateurs adorent nos services de fret\u00a0!\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d2513a elementor-widget elementor-widget-spacer\" data-id=\"6d2513a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dec3f23 elementor-widget elementor-widget-ucaddon_image_card_carousel\" data-id=\"dec3f23\" data-element_type=\"widget\" data-widget_type=\"ucaddon_image_card_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Unlimited Carousel -->\n\t\t<link id='owl-carousel-css' href='https:\/\/susi.xhddp.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\n\t\t\t<style type=\"text\/css\">\/* widget: Unlimited Carousel *\/\n\n#uc_image_card_carousel_elementor_dec3f23{\n  min-height:1px;\n}\n\n#uc_image_card_carousel_elementor_dec3f23-wrapper\n{\n  min-height:1px;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .owl-dots {\noverflow:hidden;\ndisplay:block !important;\ntext-align:center;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .owl-dot {\nborder-radius:50%;\ndisplay:inline-block;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .owl-nav .owl-prev{\n    position:absolute;\n    display:inline-block;\n    text-align:center;\n        \n}\n#uc_image_card_carousel_elementor_dec3f23 .owl-nav .owl-next{\n  position:absolute;\n  display:inline-block;\n  text-align:center;\n  }\n\n.uc_dark_carousel *{\n\tmargin:0;\n\tpadding:0;\n\t-webkit-box-sizing: border-box;\n\t-moz-box-sizing: border-box;\n\tbox-sizing: border-box;\n}\n\n.uc_dark_carousel .uc_dark_carousel_box\n{\n\tmargin:0 auto;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .uc_dark_carousel_container_holder\n{   display: flex;\n\tfont-size:14px;\n\toverflow:hidden;\n\tposition:relative;\n\twidth:100%;\n}\n\n.ue-title\n{\n\tfont-size:21px;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .uc_dark_carousel_content\n{\n  display:flex;\n  flex-direction:column;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .ue-content-bottom\n{\n  margin-top:auto;\n}\n\n#uc_image_card_carousel_elementor_dec3f23  .uc_dark_carousel_placeholder\n{\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .ue-btn-inner-wrapper\n{\n  display:flex;\n  align-items:center;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .ue-btn-inner-wrapper svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_image_card_carousel_elementor_dec3f23  .uc_dark_carousel_placeholder img\n{\n\twidth:100%;\n    transition:0.3s;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .uc_dark_carousel_content .uc_more_btn {\n\tdisplay:inline-block;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .centered .ue-item{\n\tborder: 3px solid yellow;\n}\n\n\n.ue-item-badge\n{\n  font-size:11px;\n}\n\n#uc_image_card_carousel_elementor_dec3f23 .ue-item-badge\n{\n  position:absolute;\n  right:10px;\n  top:10px;\n}\n\n\n\n\n\n<\/style>\n\n\t\t\t<div id=\"uc_image_card_carousel_elementor_dec3f23-wrapper\">\n<div class=\"uc_dark_carousel\" style=\"direction:ltr;\" >   <div class=\"uc_dark_carousel_box owl-carousel uc-items-wrapper\" id=\"uc_image_card_carousel_elementor_dec3f23\"  >\n      \n\n\n\n\n\n\n\n\n<div class=\"ue-item-holder elementor-repeater-item-53e147c\">\n  <div class=\"uc_dark_carousel_container_holder ue-item\" >\n\n    <div class=\"uc_dark_carousel_placeholder\">\n          \t<a href=\"\"  ><img decoding=\"async\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/GH94gbpHS_mid.jpg\" alt=\"GH94gbpHS_mid\"><\/a>\n  \n      \t\n        \n      \t\n\n    <\/div>\n\n          <div class=\"uc_dark_carousel_content\">\n            \t<a href=\"\"  ><div class=\"ue-title\">Bernie \u2b50\u2b50\u2b50\u2b50\u2b50<\/div><\/a>\n          <p><p>J&#039;ai achet\u00e9 une cl\u00f4ture de piscine en Chine, le vendeur m&#039;a indiqu\u00e9 le prix FOB, j&#039;ai trouv\u00e9 XING HANG, je n&#039;ai pas d&#039;entreprise aux \u00c9tats-Unis, je n&#039;ai pas pu d\u00e9charger l&#039;envoi du camion, \u00e0 la fin XING HANG a r\u00e9solu tous les probl\u00e8mes et s&#039;est assur\u00e9 que j&#039;ai re\u00e7u l&#039;envoi en toute s\u00e9curit\u00e9, je suis tr\u00e8s satisfait de leur travail.<\/p><\/p>    \n              <\/div>\n      <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n<div class=\"ue-item-holder elementor-repeater-item-06673ae\">\n  <div class=\"uc_dark_carousel_container_holder ue-item\" >\n\n    <div class=\"uc_dark_carousel_placeholder\">\n          \t<a href=\"#\"  ><img decoding=\"async\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/bu0aIqsF1_mid.jpg\" alt=\"bu0aIqsF1_mid\"><\/a>\n  \n      \t\n        \n      \t\n\n    <\/div>\n\n          <div class=\"uc_dark_carousel_content\">\n            \t<a href=\"#\"  ><div class=\"ue-title\">PJ \u2b50\u2b50\u2b50\u2b50\u2b50<\/div><\/a>\n          <p><p>Tous les colis ont bien \u00e9t\u00e9 re\u00e7us. C&#039;est la premi\u00e8re fois que j&#039;importe, j&#039;\u00e9tais nerveux au d\u00e9but, mais comme vous \u00eates guid\u00e9 ici \u00e9tape par \u00e9tape, il vous sera plus facile d&#039;importer. Ils mettent \u00e0 jour volontairement le statut de votre colis l\u00e0 o\u00f9 il se trouve actuellement. XH r\u00e9pond vraiment \u00e0 mes demandes. C&#039;est ici que j&#039;exp\u00e9die toujours mon colis. Merci XH<\/p><\/p>    \n              <\/div>\n      <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n<div class=\"ue-item-holder elementor-repeater-item-b82a53d\">\n  <div class=\"uc_dark_carousel_container_holder ue-item\" >\n\n    <div class=\"uc_dark_carousel_placeholder\">\n          \t<a href=\"#\"  ><img decoding=\"async\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Wg-oug19X_mid.jpg\" alt=\"Wg-oug19X_mid\"><\/a>\n  \n      \t\n        \n      \t\n\n    <\/div>\n\n          <div class=\"uc_dark_carousel_content\">\n            \t<a href=\"#\"  ><div class=\"ue-title\">Normand \u2b50\u2b50\u2b50\u2b50\u2b50<\/div><\/a>\n          <p><p>Nous avons achet\u00e9 une large gamme de produits de Chine vers la Pologne. Nos trois fournisseurs et nous-m\u00eames \u00e9tions tr\u00e8s inexp\u00e9riment\u00e9s en logistique. Nous ne savions pas comment exp\u00e9dier cette large gamme de produits vers la Pologne. L&#039;un des fournisseurs nous a pr\u00e9sent\u00e9 XING HANG. Il nous a donn\u00e9 la meilleure solution. Lorsque nous avons re\u00e7u la marchandise, c&#039;\u00e9tait un r\u00e9gal pour les yeux, emball\u00e9e de mani\u00e8re tr\u00e8s professionnelle, aucun dommage \u00e0 la marchandise. Nous leur en sommes tr\u00e8s reconnaissants.<\/p><\/p>    \n              <\/div>\n      <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n<div class=\"ue-item-holder elementor-repeater-item-7159479\">\n  <div class=\"uc_dark_carousel_container_holder ue-item\" >\n\n    <div class=\"uc_dark_carousel_placeholder\">\n          \t<a href=\"\"  ><img decoding=\"async\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/lmA6lob9J_mid-768x1024.jpg\" alt=\"lmA6lob9J_mid\"><\/a>\n  \n      \t\n        \n      \t\n\n    <\/div>\n\n          <div class=\"uc_dark_carousel_content\">\n            \t<a href=\"\"  ><div class=\"ue-title\">La\u00efza \u2b50\u2b50\u2b50\u2b50\u2b50<\/div><\/a>\n          <p><p>Merci beaucoup XH pour une autre transaction fluide. Ne recevez plus d&#039;\u00e9chantillons ko. Pr\u00eat \u00e0 commander une plus grande quantit\u00e9 pour la commande en gros.. Un transitaire satisfaisant avec ce service client tr\u00e8s r\u00e9actif et super accommodant. Jusqu&#039;\u00e0 la prochaine transaction po! Plus de puissance !<\/p><\/p>    \n              <\/div>\n      <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n<div class=\"ue-item-holder elementor-repeater-item-07a0f90\">\n  <div class=\"uc_dark_carousel_container_holder ue-item\" >\n\n    <div class=\"uc_dark_carousel_placeholder\">\n          \t<a href=\"#\"  ><img decoding=\"async\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/40Xw8OwIb_mid-768x1029.jpg\" alt=\"40Xw8OwIb_mid\"><\/a>\n  \n      \t\n        \n      \t\n\n    <\/div>\n\n          <div class=\"uc_dark_carousel_content\">\n            \t<a href=\"#\"  ><div class=\"ue-title\">Arnel \u2b50\u2b50\u2b50\u2b50\u2b50<\/div><\/a>\n          <p><p>Nous avons command\u00e9 26 tonnes de valves en provenance de Chine. En raison du d\u00e9lai de livraison court, nous avons d\u00fb changer le mode d&#039;exp\u00e9dition de la mer \u00e0 l&#039;air, mais \u00e0 l&#039;approche de No\u00ebl, les compagnies a\u00e9riennes manquaient beaucoup d&#039;espace. XING HANG a organis\u00e9 depuis la Chine l&#039;arriv\u00e9e de ces marchandises \u00e0 Vancouver avec succ\u00e8s en 7 jours. Je pense qu&#039;ils sont le meilleur transitaire en Chine.<\/p><\/p>    \n              <\/div>\n      <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n<div class=\"ue-item-holder elementor-repeater-item-7f89aa2\">\n  <div class=\"uc_dark_carousel_container_holder ue-item\" >\n\n    <div class=\"uc_dark_carousel_placeholder\">\n          \t<a href=\"#\"  ><img decoding=\"async\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/bcH645D-y_mid-768x576.jpg\" alt=\"bcH645D-y_mid\"><\/a>\n  \n      \t\n        \n      \t\n\n    <\/div>\n\n          <div class=\"uc_dark_carousel_content\">\n            \t<a href=\"#\"  ><div class=\"ue-title\">Karen \u2b50\u2b50\u2b50\u2b50\u2b50<\/div><\/a>\n          <p>Mon agent de machines et d&#039;\u00e9quipements de construction d&#039;entreprise \u00e0 Davao, aux Philippines, toutes nos marchandises d&#039;exp\u00e9dition sont trait\u00e9es par XING HANG, ils ont fourni la solution professionnelle et un bon prix pour nos grandes constructions, par exemple, excavatrice et grue, etc. En particulier leur riche exp\u00e9rience pour le chargement des marchandises dans le Flat Rack et le renforcement des marchandises. Nous maintiendrons une longue et bonne coop\u00e9ration avec eux \u00e0 l&#039;avenir.\n<\/p>    \n              <\/div>\n      <\/div>\n<\/div>\n\n   <\/div>\n<\/div>\n<\/div>\n\t\t\t<!-- end Unlimited Carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02fd9f9 e-flex e-con-boxed e-con e-parent\" data-id=\"02fd9f9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b64b149 elementor-widget elementor-widget-heading\" data-id=\"b64b149\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment utiliser vos services de transport de marchandises ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e293c6 elementor-widget elementor-widget-text-editor\" data-id=\"8e293c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre soci\u00e9t\u00e9 propose des services de transport de fret international de premier ordre depuis la Chine, notamment des services d&#039;entreposage, d&#039;exp\u00e9dition et de transitaire, vous offrant ainsi une solution logistique unique.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8718a78 e-flex e-con-boxed e-con e-child\" data-id=\"8718a78\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-68609d4 e-con-full e-flex e-con e-child\" data-id=\"68609d4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bef43e5 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"bef43e5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2020\/05\/1.svg\" class=\"attachment-large size-large wp-image-313\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b7145e e-con-full e-flex e-con e-child\" data-id=\"2b7145e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2683579 elementor-widget elementor-widget-heading\" data-id=\"2683579\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contactez notre service client\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f374cf8 elementor-widget elementor-widget-text-editor\" data-id=\"f374cf8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Obtenez un devis d&#039;exp\u00e9dition d\u00e9taill\u00e9 et l&#039;adresse de l&#039;entrep\u00f4t en Chine<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1dfaeb e-con-full e-flex e-con e-child\" data-id=\"f1dfaeb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ac0f78 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"3ac0f78\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2020\/05\/2.svg\" class=\"attachment-large size-large wp-image-314\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e794a7 e-con-full e-flex e-con e-child\" data-id=\"9e794a7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf14bb elementor-widget elementor-widget-heading\" data-id=\"5bf14bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Demandez au fournisseur de livrer la marchandise \u00e0 notre entrep\u00f4t\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-793a038 elementor-widget elementor-widget-text-editor\" data-id=\"793a038\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>nous p\u00e8serons tous les colis et calculerons les frais d&#039;exp\u00e9dition pour v\u00e9rifier avec vous<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1cf5b64 e-con-full e-flex e-con e-child\" data-id=\"1cf5b64\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b878c2c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b878c2c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2020\/05\/3.svg\" class=\"attachment-large size-large wp-image-315\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba0945b e-con-full e-flex e-con e-child\" data-id=\"ba0945b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecd4031 elementor-widget elementor-widget-heading\" data-id=\"ecd4031\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Confirmation de commande\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1187e15 elementor-widget elementor-widget-text-editor\" data-id=\"1187e15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une fois que le service client aura v\u00e9rifi\u00e9 les marchandises avec vous et pay\u00e9 les frais d&#039;exp\u00e9dition, les marchandises seront exp\u00e9di\u00e9es \u00e0 l&#039;adresse que vous avez indiqu\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c47f62 e-con-full e-flex e-con e-child\" data-id=\"7c47f62\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6e686a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f6e686a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2020\/05\/4.svg\" class=\"attachment-large size-large wp-image-316\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6605391 e-con-full e-flex e-con e-child\" data-id=\"6605391\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b85fb7 elementor-widget elementor-widget-heading\" data-id=\"3b85fb7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Livraison de marchandises\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ba0a35 elementor-widget elementor-widget-text-editor\" data-id=\"4ba0a35\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tout autre probl\u00e8me sera trait\u00e9 par nous, il vous suffit d&#039;attendre l&#039;arriv\u00e9e des marchandises !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7054cf8f e-con-full e-flex e-con e-parent\" data-id=\"7054cf8f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c815f60 e-con-full e-flex e-con e-child\" data-id=\"c815f60\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be78c7a elementor-widget elementor-widget-ucaddon_ue_hexagon_image_gallery\" data-id=\"be78c7a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_ue_hexagon_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- start Hexagon Grid -->\n\n\t\t\t<style type=\"text\/css\">\/* widget: Hexagon Grid *\/\n\n\n\n.e-con>.elementor-widget-ucaddon_ue_hexagon_image_gallery,\n.e-con-inner>.elementor-widget-ucaddon_ue_hexagon_image_gallery {\n  width: var(--container-widget-width);\n  --flex-grow: var(--container-widget-flex-grow);\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a.ue-hexagon-gallery {\n  --col-count: 4;\n  \t--columns-count: calc(var(--col-count) * 2 + 1);\n  display: grid;\n  grid-template-columns: repeat(var(--columns-count), 1fr);\n  opacity: 0;\n  transition: opacity 0.2s ease-in-out;\n  width: 100%;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a.ue-hexagon-gallery.uc-show {\n  opacity: 1;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item {\n  position: relative;\n  z-index: 1;\n  grid-column: span 2;\n  margin-top: -28.8675%; \n  clip-path: polygon(50% 0%, 100% 25%, 100% 75%, 50% 100%, 0 75%, 0 25%);\n  transition: all 0.25s;\n  aspect-ratio: 1 \/ 1.1547005;\n  width:100%;\n  overflow: hidden;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item-wrapper {\n  position: relative;\n  height: 100%;\n  width: 100%;\n  display: flex;\n  flex-direction: column;\n  justify-content: center;\n  align-items: center;\n  text-align:center;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item-content-wrapper {\n  display: flex;\n    flex-direction: column;\n    justify-content: center;\n  z-index: 1;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item-border {\n  position: absolute;\n  inset: 0;\n  height: 100%;\n  width: 100%;\n  background-color: transparent;\n  pointer-events: none;\n  aspect-ratio: 1 \/ 1.1547005;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item-border svg {\n  height: 100%;\n  width: 100%;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item-image {\n  position: absolute;\n  inset: 0;\n  height: 100%;\n  width: 100%;\n  z-index: 0;\n  object-fit: cover;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item:hover {\n  z-index: 3;\n}\n\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item.ue-active-item .ue-hexagon-gallery__item-image {\n  transition: transform 300ms linear;\n}\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item.ue-active-item .ue-hexagon-gallery__item-image {\n  transform: scale(1.1);\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-overlay-link {\n  position: absolute;\n  inset: 0;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-graphic-element\n{\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  line-height:1em;\n  overflow:hidden;\n  z-index: 1;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-graphic-element svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-graphic-element img\n{\n  display:block;\n}\n\n.ue-item-title\n{\n  font-size:21px;\n}\n\n@media screen and (max-width: 1024px) {\n\t#uc_ue_hexagon_image_gallery_elementor_be78c7a.ue-hexagon-gallery {\n      --col-count:  4 ;\n      --columns-count: calc(var(--col-count) * 2 + 1);\n    }\n}\n\n@media screen and (max-width: 767px) {\n\t#uc_ue_hexagon_image_gallery_elementor_be78c7a.ue-hexagon-gallery {\n      --col-count:  4  ;\n  \t  --columns-count: calc(var(--col-count) * 2 + 1);\n    }\n}\n\nbody[data-elementor-device-mode=\"desktop\"] #uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item.ue-desktop-hide {\n\tdisplay: none;\n}\n\nbody[data-elementor-device-mode=\"tablet\"] #uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item.ue-tablet-hide {\n\tdisplay: none;\n}\n\nbody[data-elementor-device-mode=\"mobile\"] #uc_ue_hexagon_image_gallery_elementor_be78c7a .ue-hexagon-gallery__item.ue-mobile-hide {\n\tdisplay: none;\n}\n\n<\/style>\n\n\t\t\t<div id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a\" class=\"ue-hexagon-gallery  uc-items-wrapper\" >\n    <div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-69ffe0f\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item1\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/ca-150x150.png\" alt=\"Exp\u00e9dition de la Chine vers le Canada\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-7e7b7ff\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item2\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/jp-150x150.png\" alt=\"Exp\u00e9dition de la Chine vers le Japon\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      <a class=\"ue-overlay-link\" href=\"https:\/\/susi.xhddp.com\/fr\/commencer-a-expedier-de-la-chine-vers-les-etats-unis-maintenant\/\" ><\/a>\n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-f357b9c\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item3\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/au-150x150.png\" alt=\"Exp\u00e9dition de la Chine vers l&#039;Australie\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-1685ef3\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item4\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/kr-150x150.png\" alt=\"Exp\u00e9dition de la Chine vers la Cor\u00e9e\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-0bd99fd\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item5\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/hk-150x150.png\" alt=\"Exp\u00e9dition de la Chine vers Hong Kong\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-015fc83\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item6\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/ph-150x150.png\" alt=\"Exp\u00e9dition de la Chine vers les Philippines\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-26f9f9f\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item7\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/sg-768x512.png\" alt=\"Exp\u00e9dition de la Chine vers Singapour\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-3c862c6\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item8\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/tw-768x512.png\" alt=\"Exp\u00e9dition de la Chine vers Taiwan\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-60ba67a\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item9\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/us-768x404.png\" alt=\"Exp\u00e9dition de la Chine vers les \u00c9tats-Unis\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-1421c41\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item10\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/vn-768x512.png\" alt=\"Exp\u00e9dition de la Chine vers le Vietnam\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-e2c5284\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item11\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/mx-768x439.png\" alt=\"Exp\u00e9dition de la Chine vers le Mexique\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-37d8132\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item12\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/gr-768x512.png\" alt=\"Exp\u00e9dition de la Chine vers la Gr\u00e8ce\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-b496614\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item13\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/de-768x461.png\" alt=\"Exp\u00e9dition de la Chine vers l&#039;Allemagne\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-1970460\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item14\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/my-768x384.png\" alt=\"Exp\u00e9dition de la Chine vers la Malaisie\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-d1b2ff3\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item15\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_the_United_Kingdom_1-2.svg-768x384.png\" alt=\"Exp\u00e9dier de la Chine vers le Royaume-Uni\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-3244172\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item16\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/fr-768x512.png\" alt=\"Exp\u00e9dition de la Chine vers la France\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-ddd08b2\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item17\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/pl-768x480.png\" alt=\"Exp\u00e9dition de la Chine vers la Pologne\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-8fb2d29\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item18\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/hu-768x384.png\" alt=\"Exp\u00e9dition de la Chine vers la Hongrie\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-d80ee35\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item19\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/ma-768x512.png\" alt=\"Exp\u00e9dition de la Chine vers le Maroc\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-d87a135\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item20\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_India.svg\" alt=\"Exp\u00e9dition de la Chine vers l&#039;Inde\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-01953b1\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item21\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_Indonesia.svg\" alt=\"Exp\u00e9dition de la Chine vers l&#039;Indon\u00e9sie\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-9549fe9\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item22\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/es-768x512.png\" alt=\"Exp\u00e9dition de la Chine vers l&#039;Espagne\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-1cc68f5\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item23\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/pt-768x512.png\" alt=\"Exp\u00e9dition de la Chine vers le Portugal\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-521a2fa\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item24\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_Slovakia.svg\" alt=\"Exp\u00e9dition de la Chine vers la Slovaquie\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-88e1cea\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item25\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_South_Africa.svg\" alt=\"Exp\u00e9dition de la Chine vers l&#039;Afrique du Sud\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-7cb43c7\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item26\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/cz-768x512.png\" alt=\"Exp\u00e9dition de la Chine vers la R\u00e9publique tch\u00e8que\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-3af83c5\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item27\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/images-4.png\" alt=\"Exp\u00e9dition de la Chine vers le Br\u00e9sil\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-5ca2119\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item28\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_Switzerland_Pantone.svg\" alt=\"Exp\u00e9dition de la Chine vers la Suisse\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-f86557a\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item29\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_the_United_Arab_Emirates.svg\" alt=\"Exp\u00e9dition de la Chine vers les \u00c9mirats arabes unis\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-ffaf60a\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item30\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_Qatar.svg-768x302.png\" alt=\"Drapeau du Qatar\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-54885bf\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item31\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_Saudi_Arabia.svg-768x513.png\" alt=\"Exp\u00e9dition de la Chine vers l&#039;Arabie saoudite\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n<div class=\"ue-hexagon-gallery__item elementor-animation-grow elementor-repeater-item-b739a0f\" data-item-id=\"uc_ue_hexagon_image_gallery_elementor_be78c7a_item32\">\n  <div class=\"ue-hexagon-gallery__item-wrapper\">\n     <img decoding=\"async\" class=\"ue-hexagon-gallery__item-image\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/Flag_of_Kuwait-1.svg\" alt=\"Drapeau du Kowe\u00eft\" \/>     <div class=\"ue-hexagon-gallery__item-content-wrapper\">\n                  \n      \n      \n      \n      \n          <\/div>\n  <\/div>\n  <\/div>\n\n  <\/div>\n\t\t\t<!-- end Hexagon Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60a50e5 e-con-full e-flex e-con e-child\" data-id=\"60a50e5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18468c8 elementor-widget elementor-widget-spacer\" data-id=\"18468c8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c71ad7 elementor-widget elementor-widget-heading\" data-id=\"3c71ad7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Contact <a class=\"wpil_keyword_link\" href=\"https:\/\/susi.xhddp.com\/fr\/\" title=\"XH\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"30\">XH<\/a> et r\u00e9duisez vos frais d&#039;exp\u00e9dition maintenant\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d72bd7f elementor-widget elementor-widget-heading\" data-id=\"d72bd7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Demander un devis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17c6e85 elementor-widget elementor-widget-wpforms\" data-id=\"17c6e85\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root {\n\t\t\t\t\t--wpforms-field-border-radius: 3px;\n--wpforms-field-background-color: #ffffff;\n--wpforms-field-border-color: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-text-color: rgba( 0, 0, 0, 0.7 );\n--wpforms-label-color: rgba( 0, 0, 0, 0.85 );\n--wpforms-label-sublabel-color: rgba( 0, 0, 0, 0.55 );\n--wpforms-label-error-color: #d63637;\n--wpforms-button-border-radius: 3px;\n--wpforms-button-background-color: #066aab;\n--wpforms-button-text-color: #ffffff;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-render-modern\" id=\"wpforms-2497\"><form id=\"wpforms-form-2497\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"2497\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/3816\" data-token=\"1886fae76abe3032702af3f7c7eebf2c\" data-trp-original-action=\"\/fr\/wp-json\/wp\/v2\/pages\/3816\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-2497-field_1-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2497-field_1\" aria-hidden=\"false\">Mise en page<\/label><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-2497-field_5-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-2497-field_5\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2497-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" aria-errormessage=\"wpforms-2497-field_5-error\" required><\/div><div id=\"wpforms-2497-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-2497-field_6\">Nom du produit<\/label><input type=\"text\" id=\"wpforms-2497-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-2497-field_6-error\" aria-describedby=\"wpforms-2497-field_6-description\" ><div id=\"wpforms-2497-field_6-description\" class=\"wpforms-field-description\">Exemple : Canap\u00e9<\/div><\/div><div id=\"wpforms-2497-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-2497-field_8\">Poids du produit<\/label><input type=\"text\" id=\"wpforms-2497-field_8\" class=\"wpforms-field-medium\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-2497-field_8-error\" aria-describedby=\"wpforms-2497-field_8-description\" ><div id=\"wpforms-2497-field_8-description\" class=\"wpforms-field-description\">Exemple : 20 kg<\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-2497-field_4-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-2497-field_4\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2497-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" spellcheck=\"false\" aria-errormessage=\"wpforms-2497-field_4-error\" required><\/div><div id=\"wpforms-2497-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-2497-field_7\"> Taille du produit<\/label><input type=\"text\" id=\"wpforms-2497-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-2497-field_7-error\" aria-describedby=\"wpforms-2497-field_7-description\" ><div id=\"wpforms-2497-field_7-description\" class=\"wpforms-field-description\">Exemple : 50*50*50cm<\/div><\/div><div id=\"wpforms-2497-field_9-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-2497-field_9\">Destination (lieu)<\/label><input type=\"text\" id=\"wpforms-2497-field_9\" class=\"wpforms-field-medium\" name=\"wpforms[fields][9]\" aria-errormessage=\"wpforms-2497-field_9-error\" aria-describedby=\"wpforms-2497-field_9-description\" ><div id=\"wpforms-2497-field_9-description\" class=\"wpforms-field-description\">Exemple : Manille<\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-2497-field_12-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-2497-field_12\">D\u00e9tails <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-2497-field_12\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][12]\" aria-errormessage=\"wpforms-2497-field_12-error\" required><\/textarea><\/div><div id=\"wpforms-2497-field_18-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"18\"><fieldset><legend class=\"wpforms-field-label\">Quel devis souhaitez-vous recevoir ?<\/legend><ul id=\"wpforms-2497-field_18\"><li class=\"choice-2 depth-1 wpforms-selected\"><input type=\"radio\" id=\"wpforms-2497-field_18_2\" name=\"wpforms[fields][18]\" value=\"Sea freight quotes\" aria-errormessage=\"wpforms-2497-field_18_2-error\"   checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-2497-field_18_2\">Devis de fret maritime<\/label><\/li><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-2497-field_18_1\" name=\"wpforms[fields][18]\" value=\"Air freight quotes\" aria-errormessage=\"wpforms-2497-field_18_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2497-field_18_1\">Devis de fret a\u00e9rien<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-2497-field_18_3\" name=\"wpforms[fields][18]\" value=\"All offers\" aria-errormessage=\"wpforms-2497-field_18_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2497-field_18_3\">Toutes les offres<\/label><\/li><\/ul><\/fieldset><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"2497\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-2497\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Soumettre<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/susi.xhddp.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3631213 e-flex e-con-boxed e-con e-parent\" data-id=\"3631213\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-601f948a ct-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"601f948a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78996e67\" data-id=\"78996e67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a821859 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"7a821859\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-3816 gallery-columns-6 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"125\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-6.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-6.png 516w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-6-300x73.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"125\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-5.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-5.png 516w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-5-300x73.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"125\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-4.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-4.png 516w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-4-300x73.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"125\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-3.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-3.png 516w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-3-300x73.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"125\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-2.png 516w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-2-300x73.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"125\" src=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-1.png 516w, https:\/\/susi.xhddp.com\/wp-content\/uploads\/2024\/11\/logo-1-300x73.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>ship of sensitive &#038; special cargo from China XH team are professional handling hazardous goods from China by air and by sea, we provide shipping rates in a short time based on MSDS and we make good plan for coming shipment goods. Besides good air freight and ocean freight for DG shipment, XH provide the [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":3547,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"footnotes":""},"class_list":["post-3816","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6},"page_title_panel":"","has_hero_section":"disabled","2b2ad8ac50aef1f7fbb376d8e8ead5dc":"","hero_section":"type-1","hero_elements":[{"id":"custom_title","enabled":true,"heading_tag":"h1","title":"Maison"},{"id":"custom_description","enabled":true,"description_visibility":{"desktop":true,"tablet":true,"mobile":false}},{"id":"custom_meta","enabled":false,"meta_elements":[{"id":"author","enabled":true,"label":"By","has_author_avatar":"yes","avatar_size":25},{"id":"post_date","enabled":true,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"updated_date","enabled":false,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"categories","enabled":false,"label":"In","style":"simple"},{"id":"comments","enabled":true}],"page_meta_elements":{"joined":true,"articles_count":true,"comments":true}},{"id":"breadcrumbs","enabled":false}],"f6202423cc1eb6422f95b230b2fc2bea":"","hero_alignment1":"CT_CSS_SKIP_RULE","hero_margin":40,"hero_alignment2":"center","hero_vertical_alignment":"center","b31e9c6021d2ddbf91b5a12d304b7655":"","hero_structure":"narrow","72c396d4ac4ae38cd8b8b39d05f1b07e":"","page_title_bg_type":"featured_image","custom_hero_background":{"attachment_id":null},"page_title_image_size":"full","parallax":{"desktop":false,"tablet":false,"mobile":false},"a04812fb6158bce62361cbf5f97ef850":"","hero_height":"250px","pageTitleFont":{"family":"Default","variation":"Default","size":"30px","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageTitleFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageMetaFont":{"family":"Default","variation":"n6","size":"12px","line-height":"1.3","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"uppercase","text-decoration":"CT_CSS_SKIP_RULE"},"pageMetaFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_font_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_background_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageExcerptFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageExcerptColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"breadcrumbsFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"breadcrumbsFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"initial":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageTitleOverlay":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"pageTitleBackground":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-6)"}}},"pageTitlePadding":{"top":"50px","bottom":"50px","left":"auto","right":"auto","linked":true},"544bddd26c409e87e1e8ddb9bd431ab9":"","page_structure_type":"default","3ca9930b3864aab1bdeb7a99166cecf8":"","content_style_source":"inherit","content_style":"wide","vertical_spacing_source":"custom","content_area_spacing":"none","background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"content_background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-8)"}}},"content_boxed_shadow":{"inherit":false,"blur":18,"spread":-6,"v_offset":12,"h_offset":0,"inset":false,"enable":true,"color":{"color":"rgba(34, 56, 101, 0.04)"}},"content_boxed_border":{"width":1,"style":"none","color":{"color":"rgba(44,62,80,0.2)"}},"content_boxed_radius":{"top":"3px","bottom":"3px","left":"3px","right":"3px","linked":true},"boxed_content_spacing":{"desktop":{"top":"40px","bottom":"40px","left":"40px","right":"40px","linked":true},"tablet":{"top":"35px","bottom":"35px","left":"35px","right":"35px","linked":true},"mobile":{"top":"20px","bottom":"20px","left":"20px","right":"20px","linked":true}},"f77482348eca000f19702ef8ae9de231":"","disable_featured_image":"no","disable_share_box":"no","disable_header":"no","disable_footer":"no"},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/susi.xhddp.com\/fr\/wp-json\/wp\/v2\/pages\/3816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/susi.xhddp.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/susi.xhddp.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/susi.xhddp.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/susi.xhddp.com\/fr\/wp-json\/wp\/v2\/comments?post=3816"}],"version-history":[{"count":0,"href":"https:\/\/susi.xhddp.com\/fr\/wp-json\/wp\/v2\/pages\/3816\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/susi.xhddp.com\/fr\/wp-json\/wp\/v2\/pages\/3547"}],"wp:attachment":[{"href":"https:\/\/susi.xhddp.com\/fr\/wp-json\/wp\/v2\/media?parent=3816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}